{"id":964,"date":"2014-09-08T19:14:03","date_gmt":"2014-09-08T17:14:03","guid":{"rendered":"https:\/\/www.editions-hope.com\/interpretation-parasomnie\/"},"modified":"2020-06-01T19:27:22","modified_gmt":"2020-06-01T17:27:22","slug":"parasomnie-interpretation","status":"publish","type":"post","link":"https:\/\/www.editions-hope.com\/en\/parasomnie-interpretation\/","title":{"rendered":"\"Parasomnie\" Interpretation"},"content":{"rendered":"[vc_row type=\"in_container\" full_screen_row_position=\"middle\" column_margin=\"default\" column_direction=\"default\" column_direction_tablet=\"default\" column_direction_phone=\"default\" scene_position=\"center\" text_color=\"dark\" text_align=\"left\" row_border_radius=\"none\" row_border_radius_applies=\"bg\" id=\"preambule\" overlay_strength=\"0.3\" gradient_direction=\"left_to_right\" shape_divider_position=\"bottom\" bg_image_animation=\"none\" shape_type=\"\"][vc_column column_padding=\"no-extra-padding\" column_padding_tablet=\"inherit\" column_padding_phone=\"inherit\" column_padding_position=\"all\" background_color_opacity=\"1\" background_hover_color_opacity=\"1\" column_shadow=\"none\" column_border_radius=\"none\" column_link_target=\"_self\" gradient_direction=\"left_to_right\" overlay_strength=\"0.3\" width=\"1\/1\" tablet_width_inherit=\"default\" tablet_text_alignment=\"default\" phone_text_alignment=\"default\" column_border_width=\"none\" column_border_style=\"solid\" bg_image_animation=\"none\"][vc_column_text css_animation=\"fadeIn\"]\n<p style=\"text-align: justify;\">Check out the new video of Warren Vidal : an interpretation of an excerpt from \"<em>Parasomnie<\/em>\" a text written by Philippe De Cuntreval.<\/p>\n<p style=\"text-align: justify;\">The story of a man who tells his sleep problems and interrogates himself about the reality that dreams can take...<\/p>\n<p style=\"text-align: justify;\">This text is an extract from the book of short stories \"<em>Claquement d'Aile<\/em>\".<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\"in_container\" full_screen_row_position=\"middle\" column_margin=\"default\" column_direction=\"default\" column_direction_tablet=\"default\" column_direction_phone=\"default\" scene_position=\"center\" text_color=\"dark\" text_align=\"left\" row_border_radius=\"none\" row_border_radius_applies=\"bg\" overlay_strength=\"0.3\" gradient_direction=\"left_to_right\" shape_divider_position=\"bottom\" bg_image_animation=\"none\"][vc_column column_padding=\"no-extra-padding\" column_padding_tablet=\"inherit\" column_padding_phone=\"inherit\" column_padding_position=\"all\" centered_text=\"true\" background_color_opacity=\"1\" background_hover_color_opacity=\"1\" column_shadow=\"none\" column_border_radius=\"none\" column_link_target=\"_self\" gradient_direction=\"left_to_right\" overlay_strength=\"0.3\" width=\"1\/1\" tablet_width_inherit=\"default\" tablet_text_alignment=\"default\" phone_text_alignment=\"default\" column_border_width=\"none\" column_border_style=\"solid\" bg_image_animation=\"none\"][nectar_video_lightbox link_style=\"play_button_with_text\" nectar_play_button_color=\"Extra-Color-1\" nectar_play_button_style=\"default\" font_style=\"p\" video_url=\"https:\/\/youtu.be\/sqESD94EjXc\" link_text=\"Watch the video\"][divider line_type=\"No Line\" custom_height=\"20px\"][\/vc_column][\/vc_row][vc_row type=\"in_container\" full_screen_row_position=\"middle\" column_margin=\"default\" column_direction=\"default\" column_direction_tablet=\"default\" column_direction_phone=\"default\" scene_position=\"center\" text_color=\"dark\" text_align=\"left\" row_border_radius=\"none\" row_border_radius_applies=\"bg\" overlay_strength=\"0.3\" gradient_direction=\"left_to_right\" shape_divider_position=\"bottom\" bg_image_animation=\"none\"][vc_column column_padding=\"no-extra-padding\" column_padding_tablet=\"inherit\" column_padding_phone=\"inherit\" column_padding_position=\"all\" background_color_opacity=\"1\" background_hover_color_opacity=\"1\" column_shadow=\"none\" column_border_radius=\"none\" column_link_target=\"_self\" gradient_direction=\"left_to_right\" overlay_strength=\"0.3\" width=\"1\/2\" tablet_width_inherit=\"default\" tablet_text_alignment=\"default\" phone_text_alignment=\"default\" column_border_width=\"none\" column_border_style=\"solid\" bg_image_animation=\"none\"]<div class=\"nectar-social hover\" data-position=\"left\" data-color-override=\"override\"><span class=\"share-btn\"> <i class=\"icon-default-style steadysets-icon-share\"><\/i> Share<\/span><div class=\"nectar-social-inner\"><a class='facebook-share nectar-sharing' href='#' title='Share this'>  <i class='fa fa-facebook'><\/i> <span class='social-text'>Share<\/span> <\/a><a class='twitter-share nectar-sharing' href='#' title='Share this'> <i class='fa icon-salient-x-twitter'><\/i> <span class='social-text'>Share<\/span> <\/a><a class='linkedin-share nectar-sharing' href='#' title='Share this'> <i class='fa fa-linkedin'><\/i> <span class='social-text'>Share<\/span> <\/a><a class='pinterest-share nectar-sharing' href='#' title='Pin this'> <i class='fa fa-pinterest'><\/i> <span class='social-text'>Pin<\/span> <\/a><\/div><div class=\"nectar-love-button\"><a href=\"#\" class=\"nectar-love\" id=\"nectar-love-964\" title=\"Love this\"> <i class=\"icon-salient-heart-2\"><\/i><span class=\"love-text\">Love<\/span><span class=\"total_loves\"><span class=\"nectar-love-count\">2<\/span><\/span><\/a><\/div><\/div>[\/vc_column][vc_column column_padding=\"no-extra-padding\" column_padding_tablet=\"inherit\" column_padding_phone=\"inherit\" column_padding_position=\"all\" background_color_opacity=\"1\" background_hover_color_opacity=\"1\" column_shadow=\"none\" column_border_radius=\"none\" column_link_target=\"_self\" gradient_direction=\"left_to_right\" overlay_strength=\"0.3\" width=\"1\/2\" tablet_width_inherit=\"default\" tablet_text_alignment=\"default\" phone_text_alignment=\"default\" column_border_width=\"none\" column_border_style=\"solid\" bg_image_animation=\"none\"][nectar_btn size=\"small\" button_style=\"see-through\" button_color_2=\"Accent-Color\" color_override=\"#8e9cad\" icon_family=\"fontawesome\" el_class=\"alignright\" text=\"Leave a comment\" url=\"#respond\" css_animation=\"swing\" icon_fontawesome=\"fa fa-comment-o\"][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=\"in_container\" full_screen_row_position=\"middle\" column_margin=\"default\" column_direction=\"default\" column_direction_tablet=\"default\" column_direction_phone=\"default\" scene_position=\"center\" text_color=\"dark\" text_align=\"left\" row_border_radius=\"none\" row_border_radius_applies=\"bg\" id=\"preambule\" overlay_strength=\"0.3\" gradient_direction=\"left_to_right\" shape_divider_position=\"bottom\" bg_image_animation=\"none\" shape_type=\"\"][vc_column column_padding=\"no-extra-padding\" column_padding_tablet=\"inherit\" column_padding_phone=\"inherit\" column_padding_position=\"all\" background_color_opacity=\"1\" background_hover_color_opacity=\"1\" column_shadow=\"none\" column_border_radius=\"none\" column_link_target=\"_self\" gradient_direction=\"left_to_right\" overlay_strength=\"0.3\" width=\"1\/1\"...<\/p>\n","protected":false},"author":3,"featured_media":959,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32],"tags":[],"class_list":{"0":"post-964","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-news-about-authors"},"jetpack_featured_media_url":"https:\/\/www.editions-hope.com\/wp-content\/uploads\/editions-hope_featured-image_blog-2014-09.jpg","_links":{"self":[{"href":"https:\/\/www.editions-hope.com\/en\/wp-json\/wp\/v2\/posts\/964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.editions-hope.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.editions-hope.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.editions-hope.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.editions-hope.com\/en\/wp-json\/wp\/v2\/comments?post=964"}],"version-history":[{"count":0,"href":"https:\/\/www.editions-hope.com\/en\/wp-json\/wp\/v2\/posts\/964\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.editions-hope.com\/en\/wp-json\/wp\/v2\/media\/959"}],"wp:attachment":[{"href":"https:\/\/www.editions-hope.com\/en\/wp-json\/wp\/v2\/media?parent=964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.editions-hope.com\/en\/wp-json\/wp\/v2\/categories?post=964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.editions-hope.com\/en\/wp-json\/wp\/v2\/tags?post=964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}